
{"id":9414,"date":"2022-11-24T11:42:24","date_gmt":"2022-11-24T11:42:24","guid":{"rendered":"https:\/\/eu.mydrap.com\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/"},"modified":"2022-11-23T15:09:24","modified_gmt":"2022-11-23T15:09:24","slug":"set-per-12-ospiti-in-tessuto-grigio-perla","status":"publish","type":"product","link":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/","title":{"rendered":"Set per 12 ospiti in tessuto grigio perla"},"content":{"rendered":"<p>Tessuto 100% naturale e di qualit\u00e0 superiore che offre il massimo assorbimento e resistenza senza rinunciare a una sensazione morbida e piacevole al tatto. Un\u2019elegante alternativa ai tovaglioli di carta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Set per 12 ospiti in color grigio perla e 100 % cotone. Composto da:<br \/>\n    \u00b7 1 rotolo da 12 tovaglioli 30&#215;30 cm<br \/>\n    \u00b7 1 rotolo da 12 tovagliette 48&#215;32 cm<\/p>\n<p>La selezione perfetta per vestire la tua tavola, che sia per un pasto in famiglia, un pranzo o una cena con ospiti. Ideale per ogni tipo di occasione ed evento formale a casa.<\/p>\n","protected":false},"featured_media":8320,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[251],"product_tag":[],"class_list":{"0":"post-9414","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sets-it","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Set di tovaglioli e tovagliette per 12 ospiti. Color grigio perla - Acquista online - MYDRAP<\/title>\n<meta name=\"description\" content=\"Set per 12 ospiti composto da tovaglioli e tovagliette in tessuto color grigio perla.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Set di tovaglioli e tovagliette per 12 ospiti. Color grigio perla - Acquista online - MYDRAP\" \/>\n<meta property=\"og:description\" content=\"Set per 12 ospiti composto da tovaglioli e tovagliette in tessuto color grigio perla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/\" \/>\n<meta property=\"og:site_name\" content=\"MY DRAP\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.mydrap.com\/wp-content\/uploads\/304-Pearl-Grey_01_Web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/\",\"name\":\"Set di tovaglioli e tovagliette per 12 ospiti. Color grigio perla - Acquista online - MYDRAP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/304-Pearl-Grey_01_Web.jpg\",\"datePublished\":\"2022-11-24T11:42:24+00:00\",\"description\":\"Set per 12 ospiti composto da tovaglioli e tovagliette in tessuto color grigio perla.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/304-Pearl-Grey_01_Web.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/304-Pearl-Grey_01_Web.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Set per 12 ospiti in tessuto grigio perla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/set-per-12-ospiti-in-tessuto-grigio-perla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Set per 12 ospiti in tessuto grigio perla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/\",\"name\":\"MY DRAP\",\"description\":\"El detalle que marca la diferencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#organization\",\"name\":\"MY DRAP\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/logo_mydrap.png.webp\",\"contentUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/logo_mydrap.png.webp\",\"width\":182,\"height\":60,\"caption\":\"MY DRAP\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Set di tovaglioli e tovagliette per 12 ospiti. Color grigio perla - Acquista online - MYDRAP","description":"Set per 12 ospiti composto da tovaglioli e tovagliette in tessuto color grigio perla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/","og_locale":"it_IT","og_type":"article","og_title":"Set di tovaglioli e tovagliette per 12 ospiti. Color grigio perla - Acquista online - MYDRAP","og_description":"Set per 12 ospiti composto da tovaglioli e tovagliette in tessuto color grigio perla.","og_url":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/","og_site_name":"MY DRAP","og_image":[{"width":1920,"height":1920,"url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/304-Pearl-Grey_01_Web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/","url":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/","name":"Set di tovaglioli e tovagliette per 12 ospiti. Color grigio perla - Acquista online - MYDRAP","isPartOf":{"@id":"https:\/\/eu.mydrap.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/#primaryimage"},"image":{"@id":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/304-Pearl-Grey_01_Web.jpg","datePublished":"2022-11-24T11:42:24+00:00","description":"Set per 12 ospiti composto da tovaglioli e tovagliette in tessuto color grigio perla.","breadcrumb":{"@id":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/#primaryimage","url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/304-Pearl-Grey_01_Web.jpg","contentUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/304-Pearl-Grey_01_Web.jpg","width":1920,"height":1920,"caption":"Set per 12 ospiti in tessuto grigio perla"},{"@type":"BreadcrumbList","@id":"https:\/\/eu.mydrap.com\/it\/producto\/set-per-12-ospiti-in-tessuto-grigio-perla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eu.mydrap.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/eu.mydrap.com\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Set per 12 ospiti in tessuto grigio perla"}]},{"@type":"WebSite","@id":"https:\/\/eu.mydrap.com\/it\/#website","url":"https:\/\/eu.mydrap.com\/it\/","name":"MY DRAP","description":"El detalle que marca la diferencia","publisher":{"@id":"https:\/\/eu.mydrap.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.mydrap.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/eu.mydrap.com\/it\/#organization","name":"MY DRAP","url":"https:\/\/eu.mydrap.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/eu.mydrap.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/logo_mydrap.png.webp","contentUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/logo_mydrap.png.webp","width":182,"height":60,"caption":"MY DRAP"},"image":{"@id":"https:\/\/eu.mydrap.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product\/9414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/media\/8320"}],"wp:attachment":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/media?parent=9414"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product_brand?post=9414"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product_cat?post=9414"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product_tag?post=9414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}