
{"id":9348,"date":"2022-11-25T07:26:22","date_gmt":"2022-11-25T07:26:22","guid":{"rendered":"https:\/\/eu.mydrap.com\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/"},"modified":"2022-11-25T07:52:48","modified_gmt":"2022-11-25T07:52:48","slug":"tovagliolo-di-stoffa-da-cocktail-blu-nebbia","status":"publish","type":"product","link":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/","title":{"rendered":"Tovagliolo di stoffa da cocktail blu nebbia"},"content":{"rendered":"<p>Tessuto 100 % naturale e di qualit\u00e0 superiore che offre il massimo assorbimento e resistenza senza rinunciare a una sensazione morbida e piacevole al tatto. Un\u2019elegante alternativa ai tovaglioli di carta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rotolo da 50 tovaglioli di stoffa 11&#215;11 cm di colore blu nebbia e 100 % cotone. Il tovagliolo ideale per cocktail e aperitivi. Grazie alle sue dimensioni pu\u00f2 essere utilizzato anche come sottobicchiere o decorazione da tavolo.<\/p>\n","protected":false},"featured_media":2542,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[246],"product_tag":[],"class_list":{"0":"post-9348","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tovagliolo-di-stoffa","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tovagliolo di stoffa da cocktail. Blu nebbia - Acquista online - MYDRAP<\/title>\n<meta name=\"description\" content=\"Tovaglioli di stoffa da cocktail color blu nebbia. Rotolo da 50 pezzi 11x11 cm, 100 % cotone, morbido e piacevole al tatto, ideali per cocktail e aperitivi. Provali!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tovagliolo di stoffa da cocktail. Blu nebbia - Acquista online - MYDRAP\" \/>\n<meta property=\"og:description\" content=\"Tovaglioli di stoffa da cocktail color blu nebbia. Rotolo da 50 pezzi 11x11 cm, 100 % cotone, morbido e piacevole al tatto, ideali per cocktail e aperitivi. Provali!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/\" \/>\n<meta property=\"og:site_name\" content=\"MY DRAP\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T07:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL1111-A-R08N-410_Cotton_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/\",\"name\":\"Tovagliolo di stoffa da cocktail. Blu nebbia - Acquista online - MYDRAP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/SL1111-A-R08N-410_Cotton_00.jpg\",\"datePublished\":\"2022-11-25T07:26:22+00:00\",\"dateModified\":\"2022-11-25T07:52:48+00:00\",\"description\":\"Tovaglioli di stoffa da cocktail color blu nebbia. Rotolo da 50 pezzi 11x11 cm, 100 % cotone, morbido e piacevole al tatto, ideali per cocktail e aperitivi. Provali!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/SL1111-A-R08N-410_Cotton_00.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/SL1111-A-R08N-410_Cotton_00.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Tovagliolo di stoffa da cocktail blu nebbia 11x11\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/producto\\\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tovagliolo di stoffa da cocktail blu nebbia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/\",\"name\":\"MY DRAP\",\"description\":\"El detalle que marca la diferencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#organization\",\"name\":\"MY DRAP\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/logo_mydrap.png.webp\",\"contentUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/logo_mydrap.png.webp\",\"width\":182,\"height\":60,\"caption\":\"MY DRAP\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tovagliolo di stoffa da cocktail. Blu nebbia - Acquista online - MYDRAP","description":"Tovaglioli di stoffa da cocktail color blu nebbia. Rotolo da 50 pezzi 11x11 cm, 100 % cotone, morbido e piacevole al tatto, ideali per cocktail e aperitivi. Provali!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/","og_locale":"it_IT","og_type":"article","og_title":"Tovagliolo di stoffa da cocktail. Blu nebbia - Acquista online - MYDRAP","og_description":"Tovaglioli di stoffa da cocktail color blu nebbia. Rotolo da 50 pezzi 11x11 cm, 100 % cotone, morbido e piacevole al tatto, ideali per cocktail e aperitivi. Provali!","og_url":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/","og_site_name":"MY DRAP","article_modified_time":"2022-11-25T07:52:48+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL1111-A-R08N-410_Cotton_00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/","url":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/","name":"Tovagliolo di stoffa da cocktail. Blu nebbia - Acquista online - MYDRAP","isPartOf":{"@id":"https:\/\/eu.mydrap.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/#primaryimage"},"image":{"@id":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL1111-A-R08N-410_Cotton_00.jpg","datePublished":"2022-11-25T07:26:22+00:00","dateModified":"2022-11-25T07:52:48+00:00","description":"Tovaglioli di stoffa da cocktail color blu nebbia. Rotolo da 50 pezzi 11x11 cm, 100 % cotone, morbido e piacevole al tatto, ideali per cocktail e aperitivi. Provali!","breadcrumb":{"@id":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/#primaryimage","url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL1111-A-R08N-410_Cotton_00.jpg","contentUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL1111-A-R08N-410_Cotton_00.jpg","width":1920,"height":1920,"caption":"Tovagliolo di stoffa da cocktail blu nebbia 11x11"},{"@type":"BreadcrumbList","@id":"https:\/\/eu.mydrap.com\/it\/producto\/tovagliolo-di-stoffa-da-cocktail-blu-nebbia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eu.mydrap.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/eu.mydrap.com\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Tovagliolo di stoffa da cocktail blu nebbia"}]},{"@type":"WebSite","@id":"https:\/\/eu.mydrap.com\/it\/#website","url":"https:\/\/eu.mydrap.com\/it\/","name":"MY DRAP","description":"El detalle que marca la diferencia","publisher":{"@id":"https:\/\/eu.mydrap.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.mydrap.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/eu.mydrap.com\/it\/#organization","name":"MY DRAP","url":"https:\/\/eu.mydrap.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/eu.mydrap.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/logo_mydrap.png.webp","contentUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/logo_mydrap.png.webp","width":182,"height":60,"caption":"MY DRAP"},"image":{"@id":"https:\/\/eu.mydrap.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product\/9348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/media\/2542"}],"wp:attachment":[{"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/media?parent=9348"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product_brand?post=9348"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product_cat?post=9348"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.mydrap.com\/it\/wp-json\/wp\/v2\/product_tag?post=9348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}