
{"id":7517,"date":"2022-11-25T07:27:17","date_gmt":"2022-11-25T07:27:17","guid":{"rendered":"https:\/\/eu.mydrap.com\/producto\/servilletas-de-tela-en-lino-para-evento-crudo\/"},"modified":"2023-11-06T12:43:52","modified_gmt":"2023-11-06T12:43:52","slug":"servilletas-de-tela-para-evento-crudo-2","status":"publish","type":"product","link":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/","title":{"rendered":"Servilletas de tela para evento crudo"},"content":{"rendered":"<p>Tejido 100 % natural y de primera calidad que aporta m\u00e1xima absorci\u00f3n y resistencia sin renunciar a un tacto suave y agradable. Una alternativa elegante a las servilletas de papel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rollo de 20 servilletas de tela de 20&#215;20 cm en color crudo y 50% algod\u00f3n &#8211; 50% lino. La servilleta m\u00e1s polivalente. Es perfecta para c\u00f3cteles, aperitivos, brunch, fiestas y en el d\u00eda a d\u00eda.<\/p>\n","protected":false},"featured_media":3151,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[83],"product_tag":[],"class_list":["post-7517","product","type-product","status-publish","has-post-thumbnail","product_cat-servilletas-de-tela","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servilletas de tela para evento. Color crudo - Comprar online - MYDRAP<\/title>\n<meta name=\"description\" content=\"Servilletas de tela para evento color crudo. Rollo de 20 uds de 20x20 cm, 50% algod\u00f3n - 50% lino de tacto suave y agradable, ideales para almuerzos y eventos informales \u00a1Pru\u00e9balas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servilletas de tela para evento. Color crudo - Comprar online - MYDRAP\" \/>\n<meta property=\"og:description\" content=\"Servilletas de tela para evento color crudo. Rollo de 20 uds de 20x20 cm, 50% algod\u00f3n - 50% lino de tacto suave y agradable, ideales para almuerzos y eventos informales \u00a1Pru\u00e9balas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"MY DRAP\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T12:43:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL2020-L-R06N-104_Linen_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/\",\"name\":\"Servilletas de tela para evento. Color crudo - Comprar online - MYDRAP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/SL2020-L-R06N-104_Linen_01.jpg\",\"datePublished\":\"2022-11-25T07:27:17+00:00\",\"dateModified\":\"2023-11-06T12:43:52+00:00\",\"description\":\"Servilletas de tela para evento color crudo. Rollo de 20 uds de 20x20 cm, 50% algod\u00f3n - 50% lino de tacto suave y agradable, ideales para almuerzos y eventos informales \u00a1Pru\u00e9balas!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/SL2020-L-R06N-104_Linen_01.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/SL2020-L-R06N-104_Linen_01.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Servilletas de tela para evento crudo 20x20\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/producto\\\/servilletas-de-tela-para-evento-crudo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servilletas de tela para evento crudo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/\",\"name\":\"MY DRAP\",\"description\":\"El detalle que marca la diferencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/#organization\",\"name\":\"MY DRAP\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/logo_mydrap.png.webp\",\"contentUrl\":\"https:\\\/\\\/eu.mydrap.com\\\/wp-content\\\/uploads\\\/logo_mydrap.png.webp\",\"width\":182,\"height\":60,\"caption\":\"MY DRAP\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.mydrap.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servilletas de tela para evento. Color crudo - Comprar online - MYDRAP","description":"Servilletas de tela para evento color crudo. Rollo de 20 uds de 20x20 cm, 50% algod\u00f3n - 50% lino de tacto suave y agradable, ideales para almuerzos y eventos informales \u00a1Pru\u00e9balas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/","og_locale":"es_ES","og_type":"article","og_title":"Servilletas de tela para evento. Color crudo - Comprar online - MYDRAP","og_description":"Servilletas de tela para evento color crudo. Rollo de 20 uds de 20x20 cm, 50% algod\u00f3n - 50% lino de tacto suave y agradable, ideales para almuerzos y eventos informales \u00a1Pru\u00e9balas!","og_url":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/","og_site_name":"MY DRAP","article_modified_time":"2023-11-06T12:43:52+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL2020-L-R06N-104_Linen_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/","url":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/","name":"Servilletas de tela para evento. Color crudo - Comprar online - MYDRAP","isPartOf":{"@id":"https:\/\/eu.mydrap.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/#primaryimage"},"image":{"@id":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL2020-L-R06N-104_Linen_01.jpg","datePublished":"2022-11-25T07:27:17+00:00","dateModified":"2023-11-06T12:43:52+00:00","description":"Servilletas de tela para evento color crudo. Rollo de 20 uds de 20x20 cm, 50% algod\u00f3n - 50% lino de tacto suave y agradable, ideales para almuerzos y eventos informales \u00a1Pru\u00e9balas!","breadcrumb":{"@id":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/#primaryimage","url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL2020-L-R06N-104_Linen_01.jpg","contentUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/SL2020-L-R06N-104_Linen_01.jpg","width":1920,"height":1920,"caption":"Servilletas de tela para evento crudo 20x20"},{"@type":"BreadcrumbList","@id":"https:\/\/eu.mydrap.com\/es\/producto\/servilletas-de-tela-para-evento-crudo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eu.mydrap.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/eu.mydrap.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Servilletas de tela para evento crudo"}]},{"@type":"WebSite","@id":"https:\/\/eu.mydrap.com\/es\/#website","url":"https:\/\/eu.mydrap.com\/es\/","name":"MY DRAP","description":"El detalle que marca la diferencia","publisher":{"@id":"https:\/\/eu.mydrap.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.mydrap.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eu.mydrap.com\/es\/#organization","name":"MY DRAP","url":"https:\/\/eu.mydrap.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eu.mydrap.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/logo_mydrap.png.webp","contentUrl":"https:\/\/eu.mydrap.com\/wp-content\/uploads\/logo_mydrap.png.webp","width":182,"height":60,"caption":"MY DRAP"},"image":{"@id":"https:\/\/eu.mydrap.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/product\/7517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/media\/3151"}],"wp:attachment":[{"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/media?parent=7517"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/product_brand?post=7517"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/product_cat?post=7517"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.mydrap.com\/es\/wp-json\/wp\/v2\/product_tag?post=7517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}